{"id":266,"date":"2017-11-01T09:03:00","date_gmt":"2017-11-01T13:03:00","guid":{"rendered":"http:\/\/www.bicebebolivia.com\/blog\/?p=266"},"modified":"2017-11-01T09:03:00","modified_gmt":"2017-11-01T13:03:00","slug":"la-bienal-del-cartel-tendra-nutrido-debate-academico","status":"publish","type":"post","link":"https:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/","title":{"rendered":"La Bienal del Cartel tendr\u00e1 un nutrido debate acad\u00e9mico"},"content":{"rendered":"<blockquote><p><em>Durante tres d\u00edas de noviembre La Paz recibir\u00e1 a docentes de toda la regi\u00f3n para la tercera versi\u00f3n del simposio acad\u00e9mico sobre ense\u00f1anza de dise\u00f1o.<\/em><\/p><\/blockquote>\n<p><strong>La Paz, 01 de noviembre.- <\/strong>La Bienal del Cartel Bolivia BICeB\u00e9 fuera de sus exhibiciones, talleres y el Congreso Internacional de Dise\u00f1o organiza el tercer simposio acad\u00e9mico sobre ense\u00f1anza en dise\u00f1o que traer\u00e1 al pa\u00eds a 60 docentes de universidades de la regi\u00f3n como son Colombia, Ecuador, Argentina, Per\u00fa, M\u00e9xico y Bolivia en La Paz desde el 21 hasta el 23 de noviembre en la Universidad Cat\u00f3lica de Bolivia (UCB).<\/p>\n<p>\u201cEs importante dialogar sobre estas investigaciones en dise\u00f1o para fortalecer el crecimiento de la profesi\u00f3n y contribuir en la divulgaci\u00f3n de conocimiento. As\u00ed mismo, promover una mejor ense\u00f1anza de la disciplina y estrechar v\u00ednculos entre docentes y sus universidades\u201d, indica la directora de la Carrera de Dise\u00f1o Gr\u00e1fico y Comunicaci\u00f3n Visual de la UCB, Cecilia Mariaca.<\/p>\n<p>El dise\u00f1o es en la actualidad una de las industrias creativas con mayor crecimiento en el pa\u00eds y esto se debe en gran parte al aporte a la sociedad que se origina desde esta disciplina.<\/p>\n<p>\u201cLa comunicaci\u00f3n visual es una parte esencial de muchas industrias creativas y la comunicaci\u00f3n estrat\u00e9gica es una teor\u00eda emergente que sirve como herramienta para facilitar comunicaciones complejas. Estas nuevas tendencias din\u00e1micas florecen, a partir de investigaciones acad\u00e9micas que influyen en el contexto\u201d, explica Mariaca, sobre la importancia de la investigaci\u00f3n en estas \u00e1reas.<\/p>\n<p>Un comit\u00e9 organizador solicita y selecciona, cada dos a\u00f1os, las ponencias enviadas por profesionales de universidades de la regi\u00f3n. La carrera de dise\u00f1o gr\u00e1fico de la UCB organiza las presentaciones adem\u00e1s de editar y producir el documento impreso de las mismas.<\/p>\n<p>\u201cEl documento final queda como una contribuci\u00f3n acad\u00e9mica para Bolivia y para el mundo\u201d, explica Mariaca.<\/p>\n<p><a href=\"http:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2017\/11\/11-CM-BiCeBelibro-patino.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-268 aligncenter\" src=\"http:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2017\/11\/11-CM-BiCeBelibro-patino-300x225.jpg\" alt=\"\" width=\"416\" height=\"312\" srcset=\"https:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2017\/11\/11-CM-BiCeBelibro-patino-300x225.jpg 300w, https:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2017\/11\/11-CM-BiCeBelibro-patino-768x576.jpg 768w, https:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2017\/11\/11-CM-BiCeBelibro-patino-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 416px) 100vw, 416px\" \/><\/a><\/p>\n<p>Este a\u00f1o en el simposio se propone discutir el rumbo que toma el dise\u00f1o en los pa\u00edses de Latinoam\u00e9rica y cuales rutas pueden considerarse v\u00e1lidas o no.<\/p>\n<p>Seg\u00fan explican miembros del comit\u00e9 organizador, se pone en debate el rol del dise\u00f1o como investigador y cual debiese ser su metodolog\u00eda surgiendo la pregunta: \u00bfte\u00f3rica, emp\u00edrica o ambas?. Los acad\u00e9micos problematizar\u00e1n la interdisciplinariedad del dise\u00f1o y su naturaleza.<\/p>\n<p>\u201cSe debe poner atenci\u00f3n en c\u00f3mo todos los factores externos han modificado el quehacer del dise\u00f1ador. La tecnolog\u00eda en muchos de los casos ha alterado la creatividad. Anteriormente si el dise\u00f1ador necesitaba una imagen la produc\u00eda con sus manos o con sus alternativas aplicando la creatividad, hoy en d\u00eda si se necesita tal imagen es tan f\u00e1cil como apegarse a Google o alg\u00fan buscador en redes, explica el texto del comit\u00e9 organizador.<\/p>\n<p>\u201cDe ser \u2013el dise\u00f1ador- un ente creativo generador de ideas eficaces, ahora se ha vuelto un ente que monta im\u00e1genes y les da un estilo\u201d, finaliza.<\/p>\n<p>Seg\u00fan dijo Mariaca la tem\u00e1ticas en debate responden a la realidad del dise\u00f1ador y la propuesta de reflexi\u00f3n esta enfocada en lograr re activar de esta manera la creatividad de los profesionales.<\/p>\n<p>Para los organizadores del evento, e dise\u00f1o ha evolucionado considerablemente desde que asumi\u00f3 el reto de profesionalizar su oficio, adem\u00e1s de conocer de manera real quien es su p\u00fablico objetivo, las caracter\u00edsticas que \u00e9ste posee y la cultura a la cual pertenece.<\/p>\n<p>Uno de los organizadores invitados de Uruguay es Gustavo Wojciechowski de la Facultad de Comunicaci\u00f3n y Dise\u00f1o de la Universidad ORT. El equipo coordinador se completa con el director de la Carrera de Arte y Dise\u00f1o Empresarial de la Universidad San Ignacio de Loyola de Lima, Per\u00fa, el profesor asociado de la Pontificia Universidad Javeriana de Cali, Colombia, Diego Berm\u00fadez, el Director General del Instituto de Estudios Superiores en Arquitectura y Dise\u00f1o de Puebla, M\u00e9xico, Osvaldo Gaona y por la Coordinadora General de la BICeB\u00e9, Susana Machicao.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante tres d\u00edas de noviembre La Paz recibir\u00e1 a docentes de toda la regi\u00f3n para la tercera versi\u00f3n del simposio acad\u00e9mico sobre ense\u00f1anza de dise\u00f1o. La Paz, 01 de noviembre.- La Bienal del Cartel Bolivia BICeB\u00e9 fuera de sus exhibiciones, talleres y el Congreso Internacional de Dise\u00f1o organiza el tercer simposio acad\u00e9mico sobre ense\u00f1anza en &hellip; <a href=\"https:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">La Bienal del Cartel tendr\u00e1 un nutrido debate acad\u00e9mico<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":267,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[44],"class_list":["post-266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-simposio-sobre-la-educacion-del-diseno","tag-bicebe-2017"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Bienal del Cartel tendr\u00e1 un nutrido debate acad\u00e9mico - BICeB\u00e9 Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Bienal del Cartel tendr\u00e1 un nutrido debate acad\u00e9mico - BICeB\u00e9 Blog\" \/>\n<meta property=\"og:description\" content=\"Durante tres d\u00edas de noviembre La Paz recibir\u00e1 a docentes de toda la regi\u00f3n para la tercera versi\u00f3n del simposio acad\u00e9mico sobre ense\u00f1anza de dise\u00f1o. La Paz, 01 de noviembre.- La Bienal del Cartel Bolivia BICeB\u00e9 fuera de sus exhibiciones, talleres y el Congreso Internacional de Dise\u00f1o organiza el tercer simposio acad\u00e9mico sobre ense\u00f1anza en &hellip; Sigue leyendo La Bienal del Cartel tendr\u00e1 un nutrido debate acad\u00e9mico\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/\" \/>\n<meta property=\"og:site_name\" content=\"BICeB\u00e9 Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BICeBe\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-01T13:03:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2017\/11\/Cecilia-Mariaca-2016-BICEBE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1181\" \/>\n\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bienal del Cartel Bolivia BICeB\u00e9\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bienal del Cartel Bolivia BICeB\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/simposio-sobre-la-educacion-del-diseno\\\/la-bienal-del-cartel-tendra-nutrido-debate-academico\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/simposio-sobre-la-educacion-del-diseno\\\/la-bienal-del-cartel-tendra-nutrido-debate-academico\\\/\"},\"author\":{\"name\":\"Bienal del Cartel Bolivia BICeB\u00e9\",\"@id\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/#\\\/schema\\\/person\\\/26ad6d9a9ae3f5b7dcc077474d935c36\"},\"headline\":\"La Bienal del Cartel tendr\u00e1 un nutrido debate acad\u00e9mico\",\"datePublished\":\"2017-11-01T13:03:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/simposio-sobre-la-educacion-del-diseno\\\/la-bienal-del-cartel-tendra-nutrido-debate-academico\\\/\"},\"wordCount\":704,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/simposio-sobre-la-educacion-del-diseno\\\/la-bienal-del-cartel-tendra-nutrido-debate-academico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Cecilia-Mariaca-2016-BICEBE.jpg\",\"keywords\":[\"BICeB\u00e9 2017\"],\"articleSection\":[\"Simposio sobre la Educaci\u00f3n del Dise\u00f1o\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/simposio-sobre-la-educacion-del-diseno\\\/la-bienal-del-cartel-tendra-nutrido-debate-academico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/simposio-sobre-la-educacion-del-diseno\\\/la-bienal-del-cartel-tendra-nutrido-debate-academico\\\/\",\"url\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/simposio-sobre-la-educacion-del-diseno\\\/la-bienal-del-cartel-tendra-nutrido-debate-academico\\\/\",\"name\":\"La Bienal del Cartel tendr\u00e1 un nutrido debate acad\u00e9mico - BICeB\u00e9 Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/simposio-sobre-la-educacion-del-diseno\\\/la-bienal-del-cartel-tendra-nutrido-debate-academico\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/simposio-sobre-la-educacion-del-diseno\\\/la-bienal-del-cartel-tendra-nutrido-debate-academico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Cecilia-Mariaca-2016-BICEBE.jpg\",\"datePublished\":\"2017-11-01T13:03:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/#\\\/schema\\\/person\\\/26ad6d9a9ae3f5b7dcc077474d935c36\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/simposio-sobre-la-educacion-del-diseno\\\/la-bienal-del-cartel-tendra-nutrido-debate-academico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/simposio-sobre-la-educacion-del-diseno\\\/la-bienal-del-cartel-tendra-nutrido-debate-academico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/simposio-sobre-la-educacion-del-diseno\\\/la-bienal-del-cartel-tendra-nutrido-debate-academico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Cecilia-Mariaca-2016-BICEBE.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/Cecilia-Mariaca-2016-BICEBE.jpg\",\"width\":1181,\"height\":1275},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/simposio-sobre-la-educacion-del-diseno\\\/la-bienal-del-cartel-tendra-nutrido-debate-academico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Bienal del Cartel tendr\u00e1 un nutrido debate acad\u00e9mico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/\",\"name\":\"BICeB\u00e9 Blog\",\"description\":\"Bienal del Cartel Bolivia 2021\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/#\\\/schema\\\/person\\\/26ad6d9a9ae3f5b7dcc077474d935c36\",\"name\":\"Bienal del Cartel Bolivia BICeB\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7a4b5272639cc73d859204e94c716e9d0dc61543d7f9a64cca5162eb3a30fabb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7a4b5272639cc73d859204e94c716e9d0dc61543d7f9a64cca5162eb3a30fabb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7a4b5272639cc73d859204e94c716e9d0dc61543d7f9a64cca5162eb3a30fabb?s=96&d=mm&r=g\",\"caption\":\"Bienal del Cartel Bolivia BICeB\u00e9\"},\"url\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/author\\\/bicebe_usser\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Bienal del Cartel tendr\u00e1 un nutrido debate acad\u00e9mico - BICeB\u00e9 Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/","og_locale":"es_ES","og_type":"article","og_title":"La Bienal del Cartel tendr\u00e1 un nutrido debate acad\u00e9mico - BICeB\u00e9 Blog","og_description":"Durante tres d\u00edas de noviembre La Paz recibir\u00e1 a docentes de toda la regi\u00f3n para la tercera versi\u00f3n del simposio acad\u00e9mico sobre ense\u00f1anza de dise\u00f1o. La Paz, 01 de noviembre.- La Bienal del Cartel Bolivia BICeB\u00e9 fuera de sus exhibiciones, talleres y el Congreso Internacional de Dise\u00f1o organiza el tercer simposio acad\u00e9mico sobre ense\u00f1anza en &hellip; Sigue leyendo La Bienal del Cartel tendr\u00e1 un nutrido debate acad\u00e9mico","og_url":"http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/","og_site_name":"BICeB\u00e9 Blog","article_publisher":"https:\/\/www.facebook.com\/BICeBe","article_published_time":"2017-11-01T13:03:00+00:00","og_image":[{"width":1181,"height":1275,"url":"https:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2017\/11\/Cecilia-Mariaca-2016-BICEBE.jpg","type":"image\/jpeg"}],"author":"Bienal del Cartel Bolivia BICeB\u00e9","twitter_misc":{"Escrito por":"Bienal del Cartel Bolivia BICeB\u00e9","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/#article","isPartOf":{"@id":"http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/"},"author":{"name":"Bienal del Cartel Bolivia BICeB\u00e9","@id":"https:\/\/www.bicebebolivia.com\/blog\/#\/schema\/person\/26ad6d9a9ae3f5b7dcc077474d935c36"},"headline":"La Bienal del Cartel tendr\u00e1 un nutrido debate acad\u00e9mico","datePublished":"2017-11-01T13:03:00+00:00","mainEntityOfPage":{"@id":"http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/"},"wordCount":704,"commentCount":0,"image":{"@id":"http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2017\/11\/Cecilia-Mariaca-2016-BICEBE.jpg","keywords":["BICeB\u00e9 2017"],"articleSection":["Simposio sobre la Educaci\u00f3n del Dise\u00f1o"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/","url":"http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/","name":"La Bienal del Cartel tendr\u00e1 un nutrido debate acad\u00e9mico - BICeB\u00e9 Blog","isPartOf":{"@id":"https:\/\/www.bicebebolivia.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/#primaryimage"},"image":{"@id":"http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2017\/11\/Cecilia-Mariaca-2016-BICEBE.jpg","datePublished":"2017-11-01T13:03:00+00:00","author":{"@id":"https:\/\/www.bicebebolivia.com\/blog\/#\/schema\/person\/26ad6d9a9ae3f5b7dcc077474d935c36"},"breadcrumb":{"@id":"http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/#primaryimage","url":"https:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2017\/11\/Cecilia-Mariaca-2016-BICEBE.jpg","contentUrl":"https:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2017\/11\/Cecilia-Mariaca-2016-BICEBE.jpg","width":1181,"height":1275},{"@type":"BreadcrumbList","@id":"http:\/\/www.bicebebolivia.com\/blog\/simposio-sobre-la-educacion-del-diseno\/la-bienal-del-cartel-tendra-nutrido-debate-academico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.bicebebolivia.com\/blog\/"},{"@type":"ListItem","position":2,"name":"La Bienal del Cartel tendr\u00e1 un nutrido debate acad\u00e9mico"}]},{"@type":"WebSite","@id":"https:\/\/www.bicebebolivia.com\/blog\/#website","url":"https:\/\/www.bicebebolivia.com\/blog\/","name":"BICeB\u00e9 Blog","description":"Bienal del Cartel Bolivia 2021","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bicebebolivia.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.bicebebolivia.com\/blog\/#\/schema\/person\/26ad6d9a9ae3f5b7dcc077474d935c36","name":"Bienal del Cartel Bolivia BICeB\u00e9","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7a4b5272639cc73d859204e94c716e9d0dc61543d7f9a64cca5162eb3a30fabb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7a4b5272639cc73d859204e94c716e9d0dc61543d7f9a64cca5162eb3a30fabb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7a4b5272639cc73d859204e94c716e9d0dc61543d7f9a64cca5162eb3a30fabb?s=96&d=mm&r=g","caption":"Bienal del Cartel Bolivia BICeB\u00e9"},"url":"https:\/\/www.bicebebolivia.com\/blog\/author\/bicebe_usser\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/posts\/266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/comments?post=266"}],"version-history":[{"count":1,"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/posts\/266\/revisions"}],"predecessor-version":[{"id":269,"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/posts\/266\/revisions\/269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/media\/267"}],"wp:attachment":[{"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/media?parent=266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/categories?post=266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/tags?post=266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}