{"id":74,"date":"2015-04-12T15:25:48","date_gmt":"2015-04-12T19:25:48","guid":{"rendered":"http:\/\/www.bicebebolivia.com\/blog\/?p=74"},"modified":"2015-04-13T19:10:08","modified_gmt":"2015-04-13T23:10:08","slug":"el-proceso-de-crecer-se-da-por-creer","status":"publish","type":"post","link":"https:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/","title":{"rendered":"El proceso de crecer se da por creer."},"content":{"rendered":"<p><strong>Apuntes sobre la pre-selecci\u00f3n de la Exhibici\u00f3n Principal BICeB\u00e9 2015<\/strong><\/p>\n<p style=\"text-align: justify;\">La BICeB\u00e9 2015 recibi\u00f3 5.814 carteles este 13 de marzo pasado; al cierre de la convocatoria, est\u00e1bamos conscientes de la tarea que se nos ven\u00eda adelante.<br \/>\nEl equipo de preselecci\u00f3n estuvo conformado por ocho profesionales: Un curador e historiador de arte, un fot\u00f3grafo, un dise\u00f1ador, un ilustrador, un artista pl\u00e1stico y tres miembros de Comit\u00e9 Organizador. Se trabaj\u00f3 durante siete jornadas, de seis horas cada una, para definir los 300 carteles seleccionados. El trabajo fue sumamente arduo y cada vez que nos acerc\u00e1bamos a determinar un ajuste de cantidades, la tarea se complejizaba inclusive m\u00e1s. Cuando logramos reducir a 600 carteles pensamos, \u00bfqu\u00e9 criterios determinar\u00edan cu\u00e1l entra y cu\u00e1l otro sale, si todos los carteles que quedan son excepcionales?; \u00bfc\u00f3mo podr\u00edamos conseguir una selecci\u00f3n lo suficientemente representativa del total recibido?; \u00bfqu\u00e9 par\u00e1metros aplicar\u00edamos para obtener los 300? <strong>Esta preselecci\u00f3n quiz\u00e1s fue una de las m\u00e1s duras que la BICeB\u00e9 ha tenido que realizar<\/strong>; los 300 carteles elegidos, absolutamente todos, han ganado su justo lugar en la selecci\u00f3n final. Los criterios han sido discutidos, evaluados, repensados, analizados y el resultado ser\u00e1 presentado a la comunidad este 20 de abril 08:00 am (-04:00 GMT).<br \/>\nEn el momento definitorio recordamos las palabras de <em>Julius Wiedemann<\/em> (Alemania), quien fuera el representante del pa\u00eds invitado y tambi\u00e9n Presidente de los jurados de la versi\u00f3n 2009: <em>\u201cCuando hago un libro de Taschen, gano muchos amigos, pero triplico la cantidad de personas que no quedan contentas con mi decisi\u00f3n\u201d<\/em>. M\u00e1s all\u00e1 de ser un proceso l\u00f3gico, al cual todos los dise\u00f1adores se exponen cuando env\u00edan sus trabajos a una convocatoria, sabemos bien \u2014por ser dise\u00f1adores nosotros mismos\u2014 de las esperanzas que uno guarda antes que la lista final sea publicada. Por ello, la responsabilidad y presi\u00f3n de las evaluaciones finales fueron a\u00fan mucho m\u00e1s duras. Al finalizar y obtener la muestra, experimentamos sentimientos encontrados: cansancio, satisfacci\u00f3n y nostalgia. \u00a1Al fin los tenemos!<br \/>\nNinguna bienal de cartel en el mundo reconoce a quienes se quedaron fuera, generalmente es una decisi\u00f3n que no se discute m\u00e1s. En \u00e9sta oportunidad la BICeB\u00e9 quiere hacerlo, porque consideramos que es parte de ese crecimiento y algo que merecen todas las personas que creen en este evento: Gracias, MUCHAS GRACIAS, por haber participado con ese gran cartel, lo vimos, lo disfrutamos y admiramos tu trabajo.<br \/>\nSentimos un <strong>profundo agradecimiento<\/strong> hacia todos y cada uno de los profesionales, dise\u00f1adores, estudiantes y simpatizantes de los 71 pa\u00edses del mundo que enviaron sus carteles a la bienal boliviana, depositando su fe en el evento y en su seriedad. Ahora trabajamos en la agenda de noviembre y pensamos en brindarles una mejor versi\u00f3n de la pr\u00f3xima BICeB\u00e9 2015 con actividades como <strong>Congreso Internacional de Dise\u00f1o<\/strong>, el <strong>Segundo Simposio Acad\u00e9mico sobre la Ense\u00f1anza del Dise\u00f1o<\/strong>, <strong>talleres de dise\u00f1o y creatividad<\/strong>, adem\u00e1s de <strong>exhibiciones<\/strong> que estamos seguros ser\u00e1n inolvidables.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apuntes sobre la pre-selecci\u00f3n de la Exhibici\u00f3n Principal BICeB\u00e9 2015 La BICeB\u00e9 2015 recibi\u00f3 5.814 carteles este 13 de marzo pasado; al cierre de la convocatoria, est\u00e1bamos conscientes de la tarea que se nos ven\u00eda adelante. El equipo de preselecci\u00f3n estuvo conformado por ocho profesionales: Un curador e historiador de arte, un fot\u00f3grafo, un dise\u00f1ador, &hellip; <a href=\"https:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">El proceso de crecer se da por creer.<\/span><\/a><\/p>\n","protected":false},"author":2,"featured_media":79,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[25,26,20],"class_list":["post-74","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria","tag-exhibicion-principal","tag-preseleccion","tag-seleccion-bicebe"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El proceso de crecer se da por creer. - BICeB\u00e9 Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El proceso de crecer se da por creer. - BICeB\u00e9 Blog\" \/>\n<meta property=\"og:description\" content=\"Apuntes sobre la pre-selecci\u00f3n de la Exhibici\u00f3n Principal BICeB\u00e9 2015 La BICeB\u00e9 2015 recibi\u00f3 5.814 carteles este 13 de marzo pasado; al cierre de la convocatoria, est\u00e1bamos conscientes de la tarea que se nos ven\u00eda adelante. El equipo de preselecci\u00f3n estuvo conformado por ocho profesionales: Un curador e historiador de arte, un fot\u00f3grafo, un dise\u00f1ador, &hellip; Sigue leyendo El proceso de crecer se da por creer.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/\" \/>\n<meta property=\"og:site_name\" content=\"BICeB\u00e9 Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BICeBe\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-12T19:25:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-04-13T23:10:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2015\/04\/03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bienal del Cartel Bolivia BICeB\u00e9\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bienal del Cartel Bolivia BICeB\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/sin-categoria\\\/el-proceso-de-crecer-se-da-por-creer\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/sin-categoria\\\/el-proceso-de-crecer-se-da-por-creer\\\/\"},\"author\":{\"name\":\"Bienal del Cartel Bolivia BICeB\u00e9\",\"@id\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/#\\\/schema\\\/person\\\/26ad6d9a9ae3f5b7dcc077474d935c36\"},\"headline\":\"El proceso de crecer se da por creer.\",\"datePublished\":\"2015-04-12T19:25:48+00:00\",\"dateModified\":\"2015-04-13T23:10:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/sin-categoria\\\/el-proceso-de-crecer-se-da-por-creer\\\/\"},\"wordCount\":523,\"commentCount\":2,\"image\":{\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/sin-categoria\\\/el-proceso-de-crecer-se-da-por-creer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/03.jpg\",\"keywords\":[\"Exhibici\u00f3n Principal\",\"Preselecci\u00f3n\",\"Seleccion BICeB\u00e9\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/sin-categoria\\\/el-proceso-de-crecer-se-da-por-creer\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/sin-categoria\\\/el-proceso-de-crecer-se-da-por-creer\\\/\",\"url\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/sin-categoria\\\/el-proceso-de-crecer-se-da-por-creer\\\/\",\"name\":\"El proceso de crecer se da por creer. - BICeB\u00e9 Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/sin-categoria\\\/el-proceso-de-crecer-se-da-por-creer\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/sin-categoria\\\/el-proceso-de-crecer-se-da-por-creer\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/03.jpg\",\"datePublished\":\"2015-04-12T19:25:48+00:00\",\"dateModified\":\"2015-04-13T23:10:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/#\\\/schema\\\/person\\\/26ad6d9a9ae3f5b7dcc077474d935c36\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/sin-categoria\\\/el-proceso-de-crecer-se-da-por-creer\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/sin-categoria\\\/el-proceso-de-crecer-se-da-por-creer\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/sin-categoria\\\/el-proceso-de-crecer-se-da-por-creer\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/03.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/03.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/sin-categoria\\\/el-proceso-de-crecer-se-da-por-creer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El proceso de crecer se da por creer.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/\",\"name\":\"BICeB\u00e9 Blog\",\"description\":\"Bienal del Cartel Bolivia 2021\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/#\\\/schema\\\/person\\\/26ad6d9a9ae3f5b7dcc077474d935c36\",\"name\":\"Bienal del Cartel Bolivia BICeB\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7a4b5272639cc73d859204e94c716e9d0dc61543d7f9a64cca5162eb3a30fabb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7a4b5272639cc73d859204e94c716e9d0dc61543d7f9a64cca5162eb3a30fabb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7a4b5272639cc73d859204e94c716e9d0dc61543d7f9a64cca5162eb3a30fabb?s=96&d=mm&r=g\",\"caption\":\"Bienal del Cartel Bolivia BICeB\u00e9\"},\"url\":\"https:\\\/\\\/www.bicebebolivia.com\\\/blog\\\/author\\\/bicebe_usser\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El proceso de crecer se da por creer. - BICeB\u00e9 Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/","og_locale":"es_ES","og_type":"article","og_title":"El proceso de crecer se da por creer. - BICeB\u00e9 Blog","og_description":"Apuntes sobre la pre-selecci\u00f3n de la Exhibici\u00f3n Principal BICeB\u00e9 2015 La BICeB\u00e9 2015 recibi\u00f3 5.814 carteles este 13 de marzo pasado; al cierre de la convocatoria, est\u00e1bamos conscientes de la tarea que se nos ven\u00eda adelante. El equipo de preselecci\u00f3n estuvo conformado por ocho profesionales: Un curador e historiador de arte, un fot\u00f3grafo, un dise\u00f1ador, &hellip; Sigue leyendo El proceso de crecer se da por creer.","og_url":"http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/","og_site_name":"BICeB\u00e9 Blog","article_publisher":"https:\/\/www.facebook.com\/BICeBe","article_published_time":"2015-04-12T19:25:48+00:00","article_modified_time":"2015-04-13T23:10:08+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2015\/04\/03.jpg","type":"image\/jpeg"}],"author":"Bienal del Cartel Bolivia BICeB\u00e9","twitter_misc":{"Escrito por":"Bienal del Cartel Bolivia BICeB\u00e9","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/#article","isPartOf":{"@id":"http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/"},"author":{"name":"Bienal del Cartel Bolivia BICeB\u00e9","@id":"https:\/\/www.bicebebolivia.com\/blog\/#\/schema\/person\/26ad6d9a9ae3f5b7dcc077474d935c36"},"headline":"El proceso de crecer se da por creer.","datePublished":"2015-04-12T19:25:48+00:00","dateModified":"2015-04-13T23:10:08+00:00","mainEntityOfPage":{"@id":"http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/"},"wordCount":523,"commentCount":2,"image":{"@id":"http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2015\/04\/03.jpg","keywords":["Exhibici\u00f3n Principal","Preselecci\u00f3n","Seleccion BICeB\u00e9"],"articleSection":["Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/","url":"http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/","name":"El proceso de crecer se da por creer. - BICeB\u00e9 Blog","isPartOf":{"@id":"https:\/\/www.bicebebolivia.com\/blog\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/#primaryimage"},"image":{"@id":"http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2015\/04\/03.jpg","datePublished":"2015-04-12T19:25:48+00:00","dateModified":"2015-04-13T23:10:08+00:00","author":{"@id":"https:\/\/www.bicebebolivia.com\/blog\/#\/schema\/person\/26ad6d9a9ae3f5b7dcc077474d935c36"},"breadcrumb":{"@id":"http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/#primaryimage","url":"https:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2015\/04\/03.jpg","contentUrl":"https:\/\/www.bicebebolivia.com\/blog\/wp-content\/uploads\/2015\/04\/03.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"http:\/\/www.bicebebolivia.com\/blog\/sin-categoria\/el-proceso-de-crecer-se-da-por-creer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.bicebebolivia.com\/blog\/"},{"@type":"ListItem","position":2,"name":"El proceso de crecer se da por creer."}]},{"@type":"WebSite","@id":"https:\/\/www.bicebebolivia.com\/blog\/#website","url":"https:\/\/www.bicebebolivia.com\/blog\/","name":"BICeB\u00e9 Blog","description":"Bienal del Cartel Bolivia 2021","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bicebebolivia.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.bicebebolivia.com\/blog\/#\/schema\/person\/26ad6d9a9ae3f5b7dcc077474d935c36","name":"Bienal del Cartel Bolivia BICeB\u00e9","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7a4b5272639cc73d859204e94c716e9d0dc61543d7f9a64cca5162eb3a30fabb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7a4b5272639cc73d859204e94c716e9d0dc61543d7f9a64cca5162eb3a30fabb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7a4b5272639cc73d859204e94c716e9d0dc61543d7f9a64cca5162eb3a30fabb?s=96&d=mm&r=g","caption":"Bienal del Cartel Bolivia BICeB\u00e9"},"url":"https:\/\/www.bicebebolivia.com\/blog\/author\/bicebe_usser\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/posts\/74","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/comments?post=74"}],"version-history":[{"count":19,"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/posts\/74\/revisions"}],"predecessor-version":[{"id":109,"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/posts\/74\/revisions\/109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/media\/79"}],"wp:attachment":[{"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/media?parent=74"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/categories?post=74"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bicebebolivia.com\/blog\/wp-json\/wp\/v2\/tags?post=74"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}